{"id":455,"date":"2020-09-04T09:27:58","date_gmt":"2020-09-04T09:27:58","guid":{"rendered":"http:\/\/wpdemo.archiwp.com\/maxbizz\/?page_id=455"},"modified":"2026-05-18T08:25:54","modified_gmt":"2026-05-18T08:25:54","slug":"contacto","status":"publish","type":"page","link":"https:\/\/rosslegalservices.com\/es\/contacto\/","title":{"rendered":"Contacto"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"455\" class=\"elementor elementor-455\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-86d48d0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"86d48d0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-1feabce ot-flex-column-vertical\" data-id=\"1feabce\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-030e332 elementor-widget elementor-widget-iheading\" data-id=\"030e332\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"iheading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"ot-heading\">\r\n\t        <span class=\"\">Detalles de contacto<\/span>\t        <h3 class=\"main-head\">Contacto<\/h3>\t    <\/div>\r\n\t    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-588e854 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"588e854\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Si necesita asesoramiento legal en Espa\u00f1a, nuestro equipo est\u00e1 aqu\u00ed para ayudarle. Ofrecemos asistencia legal y fiscal para extranjeros en temas de propiedad, impuestos, herencias y asuntos civiles. Contacte con nosotros y estaremos encantados de atenderle.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-130afd7 box-s1 icon-left elementor-widget elementor-widget-iiconbox2\" data-id=\"130afd7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"iiconbox2.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"icon-box icon-box-2\">\r\n\t\t\t<div class=\"icon-main\">\r\n\t\t        <svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-map-marker-alt\" viewBox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M172.268 501.67C26.97 291.031 0 269.413 0 192 0 85.961 85.961 0 192 0s192 85.961 192 192c0 77.413-26.97 99.031-172.268 309.67-9.535 13.774-29.93 13.773-39.464 0zM192 272c44.183 0 80-35.817 80-80s-35.817-80-80-80-80 35.817-80 80 35.817 80 80 80z\"><\/path><\/svg>\t        <\/div>\r\n\t        <div class=\"content-box\">\r\n\t\t\t\t<h6 class=\"title-box\">D\u00f3nde encontrarnos<\/h6>\t\t\t\t<p>Paseo de La Constituci\u00f3n Nro. 17 BJ<\/p>\t\t\t<\/div>\r\n\t    <\/div>\r\n\t    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8ab1650 box-s1 icon-left elementor-widget elementor-widget-iiconbox2\" data-id=\"8ab1650\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"iiconbox2.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"icon-box icon-box-2\">\r\n\t\t\t<div class=\"icon-main\">\r\n\t\t        <svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-phone-alt\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M497.39 361.8l-112-48a24 24 0 0 0-28 6.9l-49.6 60.6A370.66 370.66 0 0 1 130.6 204.11l60.6-49.6a23.94 23.94 0 0 0 6.9-28l-48-112A24.16 24.16 0 0 0 122.6.61l-104 24A24 24 0 0 0 0 48c0 256.5 207.9 464 464 464a24 24 0 0 0 23.4-18.6l24-104a24.29 24.29 0 0 0-14.01-27.6z\"><\/path><\/svg>\t        <\/div>\r\n\t        <div class=\"content-box\">\r\n\t\t\t\t<h6 class=\"title-box\"><a href=\"tel: 968 412 321\">Ll\u00e1manos<\/a><\/h6>\t\t\t\t<p>968 412 321<\/p>\t\t\t<\/div>\r\n\t    <\/div>\r\n\t    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f3cf3dd box-s1 icon-left elementor-widget elementor-widget-iiconbox2\" data-id=\"f3cf3dd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"iiconbox2.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"icon-box icon-box-2\">\r\n\t\t\t<div class=\"icon-main\">\r\n\t\t        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 24 24\"><path d=\"m8.75 17.612v4.638c0 .324.208.611.516.713.077.025.156.037.234.037.234 0 .46-.11.604-.306l2.713-3.692z\"><\/path><path d=\"m23.685.139c-.23-.163-.532-.185-.782-.054l-22.5 11.75c-.266.139-.423.423-.401.722.023.3.222.556.505.653l6.255 2.138 13.321-11.39-10.308 12.419 10.483 3.583c.078.026.16.04.242.04.136 0 .271-.037.39-.109.19-.116.319-.311.352-.53l2.75-18.5c.041-.28-.077-.558-.307-.722z\"><\/path><\/svg>\t        <\/div>\r\n\t        <div class=\"content-box\">\r\n\t\t\t\t<h6 class=\"title-box\"><a href=\"mailto: info@rosslegalservices.com\">Email<\/a><\/h6>\t\t\t\t<p>info@rosslegalservices.com<\/p>\t\t\t<\/div>\r\n\t    <\/div>\r\n\t    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-89ca7e2 ot-flex-column-vertical\" data-id=\"89ca7e2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4fb28a7 elementor-widget elementor-widget-image\" data-id=\"4fb28a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1920\" height=\"1280\" src=\"https:\/\/rosslegalservices.com\/wp-content\/uploads\/2026\/05\/2.jpg\" class=\"attachment-full size-full wp-image-2497\" alt=\"\" srcset=\"https:\/\/rosslegalservices.com\/wp-content\/uploads\/2026\/05\/2.jpg 1920w, https:\/\/rosslegalservices.com\/wp-content\/uploads\/2026\/05\/2-300x200.jpg 300w, https:\/\/rosslegalservices.com\/wp-content\/uploads\/2026\/05\/2-1024x683.jpg 1024w, https:\/\/rosslegalservices.com\/wp-content\/uploads\/2026\/05\/2-768x512.jpg 768w, https:\/\/rosslegalservices.com\/wp-content\/uploads\/2026\/05\/2-1536x1024.jpg 1536w, https:\/\/rosslegalservices.com\/wp-content\/uploads\/2026\/05\/2-600x400.jpg 600w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a5be57a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a5be57a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-574fa46 ot-flex-column-vertical\" data-id=\"574fa46\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-12e32dc elementor-widget elementor-widget-ictf7\" data-id=\"12e32dc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ictf7.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-shortcode maxbizz-cf7-0\">\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f11-o1\" lang=\"es-ES\" dir=\"ltr\" data-wpcf7-id=\"11\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/es\/wp-json\/wp\/v2\/pages\/455#wpcf7-f11-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formulario de contacto\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"11\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"es_ES\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f11-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<p><label> NOMBRE<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" autocomplete=\"name\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span> <\/label>\n<\/p>\n<p><label> CORREO ELECTR\u00d3NICO<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" autocomplete=\"email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span> <\/label>\n<\/p>\n<p><label> ASUNTO<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-subject\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-subject\" \/><\/span> <\/label>\n<\/p>\n<p><label> MENSAJE<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"your-message\"><\/textarea><\/span> <\/label>\n<\/p>\n<p><span id=\"wpcf7-6a97e0d66c79d-wrapper\" class=\"wpcf7-form-control-wrap campo-web-wrap\" data-cf7apps-honeypot=\"campo-web\" style=\"display: block;\n\t\t    width: 0px;\n\t\t    height: 0px;\n\t\t    padding: 0px;\n\t\t    border: 1px solid transparent;\n\t\t    display: block;\n\t\t    overflow: hidden;\n\t\t    \"><input type=\"hidden\" name=\"campo-web-random-hash\" value=\"82555897\"><label\n\t\t    for=\"wpcf7-6a97e0d66c79d-field\"\n\t\t    class=\"hp-message\"\n        >Por favor, deja este campo vac\u00edo.<\/label><input\n\t    id=\"wpcf7-6a97e0d66c79d-field\"\n\t    \n\t    class=\"wpcf7-form-control wpcf7-text\"\n\t    type=\"text\"\n\t    name=\"ren6efaydegv\"\n\t    value=\"\"\n\t    size=\"40\"\n\t    autocomplete=\"new-password\"\n\t    tabindex=\"1000\"\n    \/><\/span>\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"anti-spam\"><label><span class=\"wpcf7-quiz-label\">\u00bfCu\u00e1nto es 3 + 2?<\/span> <input size=\"40\" class=\"wpcf7-form-control wpcf7-quiz\" autocomplete=\"off\" aria-required=\"true\" aria-invalid=\"false\" type=\"text\" name=\"anti-spam\" \/><\/label><input type=\"hidden\" name=\"_wpcf7_quiz_answer_anti-spam\" value=\"0d4ec5d38e59baa4710a1d59d469f04c\" \/><\/span>\n<\/p>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"ENVIAR\" \/>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-de4c36a elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"de4c36a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f31c287 ot-flex-column-vertical\" data-id=\"f31c287\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3e66202 elementor-widget elementor-widget-google_maps\" data-id=\"3e66202\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"google_maps.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-custom-embed\">\n\t\t\t<iframe loading=\"lazy\"\n\t\t\t\t\tsrc=\"https:\/\/maps.google.com\/maps?q=P.%C2%BA%20de%20la%20Constituci%C3%B3n%2C%2017%2C%2030880%20%C3%81guilas%2C%20Murcia&#038;t=m&#038;z=10&#038;output=embed&#038;iwloc=near\"\n\t\t\t\t\ttitle=\"P.\u00ba de la Constituci\u00f3n, 17, 30880 \u00c1guilas, Murcia\"\n\t\t\t\t\taria-label=\"P.\u00ba de la Constituci\u00f3n, 17, 30880 \u00c1guilas, Murcia\"\n\t\t\t><\/iframe>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Detalles de contacto Contacto Si necesita asesoramiento legal en Espa\u00f1a, nuestro equipo est\u00e1 aqu\u00ed para ayudarle. Ofrecemos asistencia legal y fiscal para extranjeros en temas de propiedad, impuestos, herencias y asuntos civiles. Contacte con nosotros y estaremos encantados de atenderle. D\u00f3nde encontrarnos Paseo de La Constituci\u00f3n Nro. 17 BJ Ll\u00e1manos 968 412 321 Email info@rosslegalservices.com [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-455","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/rosslegalservices.com\/es\/wp-json\/wp\/v2\/pages\/455","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rosslegalservices.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/rosslegalservices.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/rosslegalservices.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rosslegalservices.com\/es\/wp-json\/wp\/v2\/comments?post=455"}],"version-history":[{"count":37,"href":"https:\/\/rosslegalservices.com\/es\/wp-json\/wp\/v2\/pages\/455\/revisions"}],"predecessor-version":[{"id":3862,"href":"https:\/\/rosslegalservices.com\/es\/wp-json\/wp\/v2\/pages\/455\/revisions\/3862"}],"wp:attachment":[{"href":"https:\/\/rosslegalservices.com\/es\/wp-json\/wp\/v2\/media?parent=455"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}